{"id":4554,"date":"2025-02-07T09:00:00","date_gmt":"2025-02-07T12:00:00","guid":{"rendered":"https:\/\/situada.online\/?p=4554"},"modified":"2025-02-20T14:27:08","modified_gmt":"2025-02-20T17:27:08","slug":"deepfakes-tecnologia-al-servicio-de-la-violencia","status":"publish","type":"post","link":"https:\/\/situada.online\/en\/deepfakes-tecnologia-al-servicio-de-la-violencia\/","title":{"rendered":"Deepfakes: Tecnolog\u00eda al servicio de la violencia"},"content":{"rendered":"<p class=\"has-text-align-left has-ast-global-color-2-color has-text-color has-link-color has-medium-font-size wp-elements-f55c99dcd71c9974e3a5d17c0771f6e2 wp-block-paragraph\"><strong>Deepfakes: Tecnolog\u00eda al servicio de la violencia<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Los deepfakes representan un desaf\u00edo para la seguridad digital al manipular la realidad y perpetuar violencia digital de g\u00e9nero, mediante inteligencia artificial. Esta tecnolog\u00eda amplifica desigualdades estructurales y expone a las personas, especialmente a las mujeres, a peligros en l\u00ednea. En una era de manipulaci\u00f3n masiva, urge reflexionar sobre c\u00f3mo proteger la verdad, dignidad y derechos de las personas en el entorno digital.<\/em><\/p>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-2b14f4e3\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:url(&quot;data:image\/svg+xml,%3Csvg width='16' height='16' viewBox='0 0 16 16' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M6.29312 16.9999L17 6.29302M14.2931 16.9999L17 14.293M-0.707031 15.9999L16.0002 -0.707153M8.00017 -0.707153L-0.706882 7.9999' stroke='black'\/%3E%3C\/svg%3E&quot;)\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El t\u00e9rmino &#8220;deepfake&#8221; surge de la combinaci\u00f3n de <em>deep<\/em>, que se refiere al aprendizaje profundo o deep learning (un \u00e1rea avanzada de la inteligencia artificial), y <em>fake<\/em>, que significa falso en ingl\u00e9s. Este t\u00e9rmino se refiere a contenidos digitales falsificados, como fotos o videos, creados mediante algoritmos de inteligencia artificial (IA) que replican patrones visuales y auditivos con un nivel de realismo asombroso.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El coraz\u00f3n de esta tecnolog\u00eda radica en las Redes Generativas Antag\u00f3nicas (Generative Adversarial Networks, GANs), desarrolladas en 2014. Estas redes funcionan enfrentando dos algoritmos de IA: una que genera contenido falso y otra que lo eval\u00faa. Este ciclo de retroalimentaci\u00f3n permite crear resultados cada vez m\u00e1s convincentes.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los deepfakes tienen varias t\u00e9cnicas de aplicaci\u00f3n: intercambian el rostro de una persona en el cuerpo de otra, sincronizan labios con audios que no fueron pronunciados por la persona, manipulan expresiones faciales y movimientos corporales para simular acciones que jam\u00e1s ocurrieron. Su capacidad para enga\u00f1ar desaf\u00eda nuestra confianza en lo que percibimos como real y abre una serie de interrogantes \u00e9ticas.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-14716f5d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Tipos_deepfake-1-1024x281.png ,https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Tipos_deepfake-1.png 780w, https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Tipos_deepfake-1.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Tipos_deepfake-1-1024x281.png\" alt=\"\" class=\"uag-image-4558\" width=\"1012\" height=\"291\" title=\"Tipos_deepfake\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Origen de los deepfakes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nacimiento de los deepfakes se remonta al desarrollo de las Redes Generativas Antag\u00f3nicas (GANs) por Ian Goodfellow en 2014, un avance que marc\u00f3 un antes y un despu\u00e9s en el campo de la inteligencia artificial. Seg\u00fan relata Goodfellow en varias entrevistas, <a href=\"https:\/\/www.deeplearning.ai\/the-batch\/ian-goodfellow-a-man-a-plan-a-gan\/\" data-type=\"link\" data-id=\"https:\/\/www.deeplearning.ai\/the-batch\/ian-goodfellow-a-man-a-plan-a-gan\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">la idea de las GANs surgi\u00f3 de una conversaci\u00f3n con amigos en un bar de Montreal<\/mark><\/a>, que lo llev\u00f3 a experimentar con c\u00f3digo esa misma noche. El resultado fue una tecnolog\u00eda capaz de generar contenido visual y auditivo con un nivel de realismo nunca antes visto.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, este avance no estuvo acompa\u00f1ado de una reflexi\u00f3n profunda sobre sus posibles impactos sociales. <a href=\"https:\/\/www.deeplearning.ai\/the-batch\/ian-goodfellow-a-man-a-plan-a-gan\/\" data-type=\"link\" data-id=\"https:\/\/www.deeplearning.ai\/the-batch\/ian-goodfellow-a-man-a-plan-a-gan\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">Goodfellow admiti\u00f3 que su enfoque estaba en la tecnolog\u00eda misma, en lugar de las aplicaciones espec\u00edficas o las consecuencias \u00e9ticas de su creaci\u00f3n<\/mark><\/a>, dejando en claro que no anticip\u00f3 los riesgos asociados con la proliferaci\u00f3n de los deepfakes, ni consider\u00f3 c\u00f3mo podr\u00edan ser utilizados contra los derechos de las personas, especialmente de las mujeres.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de reconocer los peligros, Goodfellow traspas\u00f3 gran parte de la responsabilidad a las y los usuarios, <a href=\"https:\/\/www.technologyreview.com\/2018\/02\/21\/145289\/the-ganfather-the-man-whos-given-machines-the-gift-of-imagination\/\" data-type=\"link\" data-id=\"https:\/\/www.technologyreview.com\/2018\/02\/21\/145289\/the-ganfather-the-man-whos-given-machines-the-gift-of-imagination\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">sugiriendo que las soluciones deben basarse en la educaci\u00f3n para fomentar el pensamiento cr\u00edtico a trav\u00e9s de clases de oratoria y debate<\/mark><\/a>. <em>&#8220;En el discurso y el debate, compites contra otro estudiante&#8221;<\/em>, se\u00f1al\u00f3<em>. &#8220;Piensas en c\u00f3mo formular afirmaciones enga\u00f1osas o c\u00f3mo construir afirmaciones correctas que sean muy persuasivas&#8221;<\/em>, agreg\u00f3, refiri\u00e9ndose a la detecci\u00f3n de contenido falso. Sin embargo, los riesgos trascienden este \u00e1mbito, afectando m\u00faltiples aspectos de la vida social y personal.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Esta postura refleja una visi\u00f3n tecnoc\u00e9ntrica donde las innovaciones se dise\u00f1an priorizando la productividad, mientras que las implicaciones \u00e9ticas quedan relegadas a un segundo plano. De esta reflexi\u00f3n surge una pregunta fundamental: <strong>\u00bfPuede la tecnolog\u00eda desarrollarse sin considerar de antemano el impacto, especialmente en un mundo donde las desigualdades estructurales amplifican sus riesgos?<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Da\u00f1os disfrazados de avances<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un mundo saturado de informaci\u00f3n, esta tecnolog\u00eda hace m\u00e1s dif\u00edcil distinguir lo real de lo falso, creando un terreno f\u00e9rtil para la desinformaci\u00f3n. Tambi\u00e9n representa una amenaza para la estabilidad pol\u00edtica y social, al facilitar la creaci\u00f3n de discursos falsos o eventos inexistentes. Incluso figuras conocidas han promovido este tipo de contenidos. Un ejemplo de ello es <a href=\"https:\/\/es.wired.com\/articulos\/elon-musk-comparte-un-video-manipulado-de-kamala-harris\" data-type=\"link\" data-id=\"https:\/\/es.wired.com\/articulos\/elon-musk-comparte-un-video-manipulado-de-kamala-harris\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">Elon Musk, quien difundi\u00f3 un deepfake de Kamala Harris en X<\/mark><\/a>, en el que aparec\u00eda dando discursos que nunca pronunci\u00f3.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su aparici\u00f3n, los deepfakes han sido utilizados como herramientas de violencia digital, especialmente contra las mujeres. <a href=\"https:\/\/www.realitydefender.com\/blog\/history-of-deepfakes\" data-type=\"link\" data-id=\"https:\/\/www.realitydefender.com\/blog\/history-of-deepfakes\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">La popularizaci\u00f3n de esta tecnolog\u00eda comenz\u00f3 en Reddit<\/mark><\/a>, donde un usuario llamado <em>deepfakes <\/em>cre\u00f3 videos falsos que mostraban a mujeres celebridades en situaciones sexuales (usando la t\u00e9cnica de face-swap). En la actualidad, <a href=\"https:\/\/www.securityhero.io\/state-of-deepfakes\/\" data-type=\"link\" data-id=\"https:\/\/www.securityhero.io\/state-of-deepfakes\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">el 99% del contenido sexual creado con esta tecnolog\u00eda est\u00e1 hecho sobre mujeres<\/mark><\/a>. Entre <a href=\"https:\/\/www.uoc.edu\/es\/news\/2023\/265-deepfakes-pornograficos-cuando-IA-desnuda-tu-intimidad-vulnera-tus-derechos\" data-type=\"link\" data-id=\"https:\/\/www.uoc.edu\/es\/news\/2023\/265-deepfakes-pornograficos-cuando-IA-desnuda-tu-intimidad-vulnera-tus-derechos\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#2e80f2\" class=\"has-inline-color\">2022 y 2023, la producci\u00f3n de este material aument\u00f3 un alarmante 464%<\/mark><\/a>.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n m\u00e1s utilizada de esta tecnolog\u00eda, y a su vez la m\u00e1s da\u00f1ina, ha sido la creaci\u00f3n de pornograf\u00eda no consensuada, donde los rostros de mujeres son superpuestos en cuerpos de otras mujeres desnudas, exponi\u00e9ndolas a humillaciones p\u00fablicas, chantajes y transgresiones de su intimidad. Este uso inicial de la tecnolog\u00eda dej\u00f3 claro que sus riesgos no eran solo hipot\u00e9ticos, sino una realidad devastadora para muchas, especialmente en la regi\u00f3n Latinoamericana.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, algunas voces argumentan que los deepfakes podr\u00edan tener usos positivos. Por ejemplo, en el \u00e1mbito art\u00edstico, se ha planteado la posibilidad de &#8220;revivir&#8221; a artistas fallecidos para recrear escenas y en la industria del marketing; reducir costos al permitir la creaci\u00f3n de contenido audiovisual sin necesidad de rodajes complejos. Sin embargo, estas llamadas \u201cventajas\u201d est\u00e1n lejos de ser incuestionables. Revivir digitalmente a una persona plantea dilemas \u00e9ticos sobre el consentimiento y la explotaci\u00f3n de su imagen. <strong>\u00bfC\u00f3mo garantizamos que esta pr\u00e1ctica respete la memoria y dignidad de quienes ya no est\u00e1n?<\/strong> <strong>\u00bfQui\u00e9n decide c\u00f3mo y por qu\u00e9 se utiliza su imagen?&nbsp;<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Un reflejo de las din\u00e1micas de poder en la era digital<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:0;margin-right:0;margin-bottom:0;margin-left:0\">M\u00e1s all\u00e1 de sus aplicaciones t\u00e9cnicas, los deepfakes revelan algo m\u00e1s profundo: la forma en que la tecnolog\u00eda es creada y utilizada dentro de estructuras de poder desiguales. Mientras que sus supuestos beneficios permanecen llenos de incertidumbres \u00e9ticas, sus impactos negativos son innegables, especialmente para las mujeres, quienes contin\u00faan siendo el blanco principal de la violencia digital que perpet\u00faa din\u00e1micas hist\u00f3ricas de opresi\u00f3n.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tecnolog\u00eda demuestra que las herramientas digitales no son neutrales. Los deepfakes van m\u00e1s all\u00e1 de su concepto (manipular im\u00e1genes), sino que exponen las prioridades y perspectivas de quienes las crean, evidenciando c\u00f3mo las desigualdades existentes encuentran nuevos veh\u00edculos en el entorno digital. En lugar de promover la equidad, el desarrollo tecnol\u00f3gico amplifica vulnerabilidades y refuerza jerarqu\u00edas de poder cuando no se dise\u00f1an con \u00e9tica y consciencia.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El problema no radica \u00fanicamente en los usos malintencionados de los deepfakes, sino en las prioridades mismas de su creaci\u00f3n. Tecnolog\u00edas como \u00e9sta reflejan una l\u00f3gica que privilegia la productividad y el impacto comercial, mientras minimiza sus consecuencias. En este contexto, las personas m\u00e1s vulnerables se convierten en terreno de experimentaci\u00f3n, en lugar de ser protegidas.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si queremos que la tecnolog\u00eda contribuya a la seguridad y progreso colectivo, es fundamental repensar sus objetivos y los valores que gu\u00edan su desarrollo.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-eec97851\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8a0d421a uag-hide-desktop uag-hide-tab uag-hide-mob\"><h2 class=\"uagb-heading-text\"><strong>Infograf\u00eda<\/strong><\/h2><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9751dd59 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-8afcb78c\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1167154f\"><h2 class=\"uagb-heading-text\"><strong>Deepfakes: El rostro de la nueva amenaza digital<\/strong><\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1b3c4869\">\n<div class=\"wp-block-uagb-image uagb-block-47838ac7 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Febrero-Infografia-1-1024x1024.png ,https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Febrero-Infografia-1.png 780w, https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Febrero-Infografia-1.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Febrero-Infografia-1-1024x1024.png\" alt=\"\" class=\"uag-image-4586\" width=\"1024\" height=\"1024\" title=\"Febrero Infografia (1)\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-be5aefdd\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:url(&quot;data:image\/svg+xml,%3Csvg width='16' height='16' viewBox='0 0 16 16' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M6.29312 16.9999L17 6.29302M14.2931 16.9999L17 14.293M-0.707031 15.9999L16.0002 -0.707153M8.00017 -0.707153L-0.706882 7.9999' stroke='black'\/%3E%3C\/svg%3E&quot;)\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6af21ef2\"><h2 class=\"uagb-heading-text\"><strong>Noticias<\/strong><\/h2><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-0cd21f33\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--carousel\">\n\t\t\t\t\t\t\t\t<div class=\"uagb-slick-carousel uagb-block-0cd21f33\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"4562\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia3-Linea2--1024x1024.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia3-Linea2--1024x1024.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia3-Linea2--300x300.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"4561\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia2-Linea2-1024x1024.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia2-Linea2-1024x1024.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia2-Linea2-300x300.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"4560\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia1-Linea2-1024x1024.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia1-Linea2-1024x1024.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia1-Linea2-300x300.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"4563\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia4-Linea2-2-1024x1024.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia4-Linea2-2-1024x1024.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Noticia4-Linea2-2-300x300.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">XCC<\/p>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-833cdf84\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Los deepfakes representan un desaf\u00edo para la seguridad digital al manipular la realidad y perpetuar violencia digital de g\u00e9nero, mediante inteligencia artificial. Esta tecnolog\u00eda amplifica desigualdades estructurales y expone a las personas, especialmente a las mujeres, a peligros en l\u00ednea. En una era de manipulaci\u00f3n masiva, urge reflexionar sobre c\u00f3mo proteger la verdad, dignidad y derechos de las personas en el entorno digital.<\/p>","protected":false},"author":2,"featured_media":4559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[40],"tags":[11,57,27],"class_list":["post-4554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridaddigital","tag-deepfake","tag-desinformacion","tag-seguridad-digital"],"uagb_featured_image_src":{"full":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1.png",1500,500,false],"thumbnail":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1-150x150.png",150,150,true],"medium":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1-300x100.png",300,100,true],"medium_large":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1-768x256.png",768,256,true],"large":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1-1024x341.png",1024,341,true],"1536x1536":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1.png",1500,500,false],"2048x2048":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1.png",1500,500,false],"trp-custom-language-flag":["https:\/\/situada.online\/wp-content\/uploads\/2025\/02\/Linea-2-Febrero1-18x6.png",18,6,true]},"uagb_author_info":{"display_name":"Ximena Cuzcano-Chavez","author_link":"https:\/\/situada.online\/en\/author\/ximena-cuzcano-chavez\/"},"uagb_comment_info":0,"uagb_excerpt":"Los deepfakes representan un desaf\u00edo para la seguridad digital al manipular la realidad y perpetuar violencia digital de g\u00e9nero, mediante inteligencia artificial. Esta tecnolog\u00eda amplifica desigualdades estructurales y expone a las personas, especialmente a las mujeres, a peligros en l\u00ednea. En una era de manipulaci\u00f3n masiva, urge reflexionar sobre c\u00f3mo proteger la verdad, dignidad y&hellip;","_links":{"self":[{"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/posts\/4554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/comments?post=4554"}],"version-history":[{"count":11,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/posts\/4554\/revisions"}],"predecessor-version":[{"id":4604,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/posts\/4554\/revisions\/4604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/media\/4559"}],"wp:attachment":[{"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/media?parent=4554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/categories?post=4554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/situada.online\/en\/wp-json\/wp\/v2\/tags?post=4554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}